{"id":9898,"date":"2025-06-20T05:03:00","date_gmt":"2025-06-20T05:03:00","guid":{"rendered":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/?p=9898"},"modified":"2025-05-20T09:20:48","modified_gmt":"2025-05-20T09:20:48","slug":"natursteinpflaster-gestaltung-stein-fuer-stein","status":"publish","type":"post","link":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/allgemein\/9898-natursteinpflaster-gestaltung-stein-fuer-stein\/","title":{"rendered":"Natursteinpflaster &#8211; Gestaltung Stein f\u00fcr Stein"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Schon die kleinste Fl\u00e4che kann, wenn sie mit Natursteinpflaster befestigt wird, lebhaft und abwechslungsreich gestaltet werden. Es gibt zig M\u00f6glichkeiten die sich einem bieten. Entdecken Sie hier eine kleine Auswahl.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schon die kleinste Fl\u00e4che kann, wenn sie mit Natursteinpflaster befestigt wird, lebhaft und abwechslungsreich gestaltet werden. Es gibt zig M\u00f6glichkeiten die sich einem bieten. Entdecken Sie hier eine kleine Auswahl.<\/p>\n","protected":false},"author":3,"featured_media":3459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/posts\/9898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/comments?post=9898"}],"version-history":[{"count":3,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/posts\/9898\/revisions"}],"predecessor-version":[{"id":9901,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/posts\/9898\/revisions\/9901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/media\/3459"}],"wp:attachment":[{"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/media?parent=9898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/categories?post=9898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/tags?post=9898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}