{"id":9641,"date":"2025-04-25T05:03:00","date_gmt":"2025-04-25T05:03:00","guid":{"rendered":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/?p=9641"},"modified":"2025-02-04T12:55:50","modified_gmt":"2025-02-04T12:55:50","slug":"kleinst-und-kleinmengen","status":"publish","type":"post","link":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/allgemein\/9641-kleinst-und-kleinmengen\/","title":{"rendered":"Kleinst- und Kleinmengen"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Kann man bei euch auch kleinere Mengen kaufen?<\/p>\n\n\n\n<p>Das ist eine Frage, die uns sehr oft gestellt wird. Die Antwort ist, dass zwei Pauschalen auch das Einkaufen von kleinen Mengen f\u00fcr jeden m\u00f6glich macht. Erfahren Sie hier mehr \u00fcber dieses Angebot.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kann man bei euch auch kleinere Mengen kaufen? Das ist eine Frage, die uns sehr oft gestellt wird. Die Antwort ist, dass zwei Pauschalen auch das Einkaufen von kleinen Mengen f\u00fcr jeden m\u00f6glich macht. Erfahren Sie hier mehr \u00fcber dieses Angebot.<\/p>\n","protected":false},"author":3,"featured_media":9642,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/posts\/9641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/comments?post=9641"}],"version-history":[{"count":4,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/posts\/9641\/revisions"}],"predecessor-version":[{"id":9646,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/posts\/9641\/revisions\/9646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/media\/9642"}],"wp:attachment":[{"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/media?parent=9641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/categories?post=9641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/tags?post=9641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}