{"id":10400,"date":"2026-01-09T05:03:00","date_gmt":"2026-01-09T05:03:00","guid":{"rendered":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/?p=10400"},"modified":"2026-01-09T08:26:20","modified_gmt":"2026-01-09T08:26:20","slug":"der-befahrbare-bodenbelag","status":"publish","type":"post","link":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/allgemein\/10400-der-befahrbare-bodenbelag\/","title":{"rendered":"Der befahrbare Bodenbelag"},"content":{"rendered":"\n<p>Gerne werden gepflasterte Fl\u00e4chen zum Abstellen von Fahrzeugen oder f\u00fcr Wegefl\u00e4chen verwendet. Entdecken Sie hier die M\u00f6glichkeiten, die unser Sortiment bietet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gerne werden gepflasterte Fl\u00e4chen zum Abstellen von Fahrzeugen oder f\u00fcr Wegefl\u00e4chen verwendet. Entdecken Sie hier die M\u00f6glichkeiten, die unser Sortiment bietet.<\/p>\n","protected":false},"author":3,"featured_media":9154,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/posts\/10400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/comments?post=10400"}],"version-history":[{"count":4,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/posts\/10400\/revisions"}],"predecessor-version":[{"id":10405,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/posts\/10400\/revisions\/10405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/media\/9154"}],"wp:attachment":[{"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/media?parent=10400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/categories?post=10400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weiland-mannheim.de\/erdenwerk\/wp-json\/wp\/v2\/tags?post=10400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}